{"id":6549,"date":"2016-06-09T21:26:24","date_gmt":"2016-06-09T19:26:24","guid":{"rendered":"https:\/\/www.resonnance.org\/it\/masterclass\/"},"modified":"2016-12-13T17:23:49","modified_gmt":"2016-12-13T16:23:49","slug":"masterclass","status":"publish","type":"post","link":"http:\/\/www.resonnance.org\/it\/masterclass\/","title":{"rendered":"Master classes &#8211; Informations g\u00e9n\u00e9rales"},"content":{"rendered":"<p>L&#8217;Acad\u00e9mie R\u00e9sonnance, plate-forme internationale, offre\u00a0une formation\u00a0\u00e0\u00a0la P\u00e9dagogie R\u00e9sonnance aux musiciens classiques de niveau sup\u00e9rieur, pianistes,\u00a0chanteurs, ensembles de musique de chambre, chefs d\u2019orchestre et\u00a0pianistes improvisateurs. Elle propose une dizaine de master classes annuelles\u00a0\u00e0\u00a0Morges\u00a0(Suisse), en lien avec celles dispens\u00e9es par les m\u00eames professeurs\u00a0dans toutes les filiales de la Fondation,\u00a0\u00e0\u00a0Rome, Paris,\u00a0Beyrouth, Bucarest,\u00a0Barcelone et Louvain.<\/p>\n<p>Chaque master class dure entre 3\u00a0\u00e0\u00a06 jours et\u00a0propose :<\/p>\n<ul>\n<li>la possibilit\u00e9\u00a0de travailler au\u00a0minimum\u00a0\u00e0\u00a0deux reprises avec le professeur principal et\u00a0\u00e0\u00a0deux reprises\u00a0avec un assistant\u00a0;<\/li>\n<li>une heure par jour consacr\u00e9e\u00a0\u00e0\u00a0l&#8217;\u00e9tude d&#8217;un\u00a0module th\u00e9orique sur la ph\u00e9nom\u00e9nologie du son ou du geste\u00a0;<\/li>\n<li>pour les participants au cours de direction\u00a0d&#8217;orchestre, la possibilit\u00e9\u00a0de travailler avec un ensemble form\u00e9\u00a0de musiciens de\u00a0l&#8217;OSR\u00e9, Orchestre Solidaire R\u00e9sonnance\u00a0;<\/li>\n<li>des conf\u00e9rences en lien\u00a0avec la P\u00e9dagogie R\u00e9sonnance, mais aussi sur la vie des compositeurs et des grands interpr\u00e8tes, par\u00a0des intervenants de renomm\u00e9e internationale\u00a0;<\/li>\n<li>un ou deux concerts R\u00e9sonnance dans des\u00a0lieux de solidarit\u00e9\u00a0(maisons de retraite, h\u00f4pitaux ou\u00a0institutions sp\u00e9cialis\u00e9es) en milieu ou en fin de master class.<\/li>\n<\/ul>\n<p>A l&#8217;appr\u00e9ciation des professeurs, quelques musiciens seront invit\u00e9s\u00a0\u00e0\u00a0:<\/p>\n<ul>\n<li>participer\u00a0\u00e0\u00a0l&#8217;un des deux grands concerts annuels de la Fondation R\u00e9sonnance\u00a0Suisse, soit\u00a0\u00e0\u00a0la salle Paderewski du Casino de Montbenon (Lausanne), soit au Th\u00e9\u00e2tre de\u00a0Beausobre (Morges).<\/li>\n<li>jouer leurs programmes dans les lieux de solidarit\u00e9\u00a0des filiales de\u00a0la Fondation : Rome, Barcelone, Paris, Belgique, Roumanie et Liban.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Acad\u00e9mie R\u00e9sonnance, plate-forme internationale, offre\u00a0une formation\u00a0\u00e0\u00a0la P\u00e9dagogie R\u00e9sonnance aux musiciens classiques de niveau sup\u00e9rieur, pianistes,\u00a0chanteurs, ensembles de musique de chambre, chefs d\u2019orchestre et\u00a0pianistes improvisateurs. Elle propose une dizaine de master classes annuelles\u00a0\u00e0\u00a0Morges\u00a0(Suisse), en lien avec celles dispens\u00e9es par les m\u00eames professeurs\u00a0dans toutes les filiales de la Fondation,\u00a0\u00e0\u00a0Rome, Paris,\u00a0Beyrouth, Bucarest,\u00a0Barcelone et Louvain. Chaque master class dure [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6549","post","type-post","status-publish","format-aside","hentry","category-lacademie","post_format-post-format-aside"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Master classes - Informations g\u00e9n\u00e9rales - Italie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.resonnance.org\/it\/masterclass\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Master classes - Informations g\u00e9n\u00e9rales - Italie\" \/>\n<meta property=\"og:description\" content=\"L&#8217;Acad\u00e9mie R\u00e9sonnance, plate-forme internationale, offre\u00a0une formation\u00a0\u00e0\u00a0la P\u00e9dagogie R\u00e9sonnance aux musiciens classiques de niveau sup\u00e9rieur, pianistes,\u00a0chanteurs, ensembles de musique de chambre, chefs d\u2019orchestre et\u00a0pianistes improvisateurs. Elle propose une dizaine de master classes annuelles\u00a0\u00e0\u00a0Morges\u00a0(Suisse), en lien avec celles dispens\u00e9es par les m\u00eames professeurs\u00a0dans toutes les filiales de la Fondation,\u00a0\u00e0\u00a0Rome, Paris,\u00a0Beyrouth, Bucarest,\u00a0Barcelone et Louvain. Chaque master class dure [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.resonnance.org\/it\/masterclass\/\" \/>\n<meta property=\"og:site_name\" content=\"Italie\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-09T19:26:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-13T16:23:49+00:00\" \/>\n<meta name=\"author\" content=\"jonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.resonnance.org\/it\/masterclass\/\",\"url\":\"http:\/\/www.resonnance.org\/it\/masterclass\/\",\"name\":\"Master classes - Informations g\u00e9n\u00e9rales - Italie\",\"isPartOf\":{\"@id\":\"https:\/\/www.resonnance.org\/it\/#website\"},\"datePublished\":\"2016-06-09T19:26:24+00:00\",\"dateModified\":\"2016-12-13T16:23:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.resonnance.org\/it\/masterclass\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.resonnance.org\/it\/masterclass\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.resonnance.org\/it\/masterclass\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.resonnance.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Master classes &#8211; Informations g\u00e9n\u00e9rales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.resonnance.org\/it\/#website\",\"url\":\"https:\/\/www.resonnance.org\/it\/\",\"name\":\"Italie\",\"description\":\"Un monde en R\u00e9sonnance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.resonnance.org\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb\",\"name\":\"jonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g\",\"caption\":\"jonas\"},\"url\":\"http:\/\/www.resonnance.org\/it\/author\/jonas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Master classes - Informations g\u00e9n\u00e9rales - Italie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.resonnance.org\/it\/masterclass\/","og_locale":"en_US","og_type":"article","og_title":"Master classes - Informations g\u00e9n\u00e9rales - Italie","og_description":"L&#8217;Acad\u00e9mie R\u00e9sonnance, plate-forme internationale, offre\u00a0une formation\u00a0\u00e0\u00a0la P\u00e9dagogie R\u00e9sonnance aux musiciens classiques de niveau sup\u00e9rieur, pianistes,\u00a0chanteurs, ensembles de musique de chambre, chefs d\u2019orchestre et\u00a0pianistes improvisateurs. Elle propose une dizaine de master classes annuelles\u00a0\u00e0\u00a0Morges\u00a0(Suisse), en lien avec celles dispens\u00e9es par les m\u00eames professeurs\u00a0dans toutes les filiales de la Fondation,\u00a0\u00e0\u00a0Rome, Paris,\u00a0Beyrouth, Bucarest,\u00a0Barcelone et Louvain. Chaque master class dure [&hellip;]","og_url":"http:\/\/www.resonnance.org\/it\/masterclass\/","og_site_name":"Italie","article_published_time":"2016-06-09T19:26:24+00:00","article_modified_time":"2016-12-13T16:23:49+00:00","author":"jonas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jonas","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.resonnance.org\/it\/masterclass\/","url":"http:\/\/www.resonnance.org\/it\/masterclass\/","name":"Master classes - Informations g\u00e9n\u00e9rales - Italie","isPartOf":{"@id":"https:\/\/www.resonnance.org\/it\/#website"},"datePublished":"2016-06-09T19:26:24+00:00","dateModified":"2016-12-13T16:23:49+00:00","author":{"@id":"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb"},"breadcrumb":{"@id":"http:\/\/www.resonnance.org\/it\/masterclass\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.resonnance.org\/it\/masterclass\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.resonnance.org\/it\/masterclass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.resonnance.org\/it\/"},{"@type":"ListItem","position":2,"name":"Master classes &#8211; Informations g\u00e9n\u00e9rales"}]},{"@type":"WebSite","@id":"https:\/\/www.resonnance.org\/it\/#website","url":"https:\/\/www.resonnance.org\/it\/","name":"Italie","description":"Un monde en R\u00e9sonnance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.resonnance.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb","name":"jonas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g","caption":"jonas"},"url":"http:\/\/www.resonnance.org\/it\/author\/jonas\/"}]}},"_links":{"self":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/posts\/6549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/comments?post=6549"}],"version-history":[{"count":0,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/posts\/6549\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/media?parent=6549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/categories?post=6549"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/tags?post=6549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}