{"id":6536,"date":"2016-06-23T12:37:40","date_gmt":"2016-06-23T10:37:40","guid":{"rendered":"https:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/"},"modified":"2016-12-13T17:19:48","modified_gmt":"2016-12-13T16:19:48","slug":"les-ecoles-resonnance","status":"publish","type":"post","link":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/","title":{"rendered":"\u00c9coles R\u00e9sonnance"},"content":{"rendered":"<h2>Les principes fondateurs des \u00e9coles R\u00e9sonnance<\/h2>\n<ul>\n<li><strong>La gratuit\u00e9\u00a0:\u00a0<\/strong>elle<strong>\u00a0<\/strong>est d\u2019abord un \u00e9tat int\u00e9rieur, un choix de vie qui nous apprend que seul dans la gratuit\u00e9, on a tous les talents. Pour nous, le v\u00e9ritable don ne tient pas tant \u00e0 ce que l\u2019on a re\u00e7u \u00e0 la naissance en terme de \u00ab\u00a0talent\u00a0\u00bb, qu\u2019\u00e0 ce qu\u2019on est capable d\u2019offrir avec son coeur en toute humilit\u00e9. Quels que soient les choix spirituels de chacun, c\u2019est dans cette exp\u00e9rience du don que se r\u00e9v\u00e8le la dimension juste, accessible \u00e0 tout \u00eatre humain de s\u2019\u00e9lever au-del\u00e0 des simples m\u00e9canismes naturels. La gratuit\u00e9 de l\u2019enseignement permet d\u2019\u00e9carter certaines pressions in\u00e9vitables que l\u2019argent met en jeu, notamment dans les rapports complexes entre l\u2019enseignant, l\u2019\u00e9l\u00e8ve et, le cas \u00e9ch\u00e9ant, ses parents.<\/li>\n<li><strong>L\u2019absence de limite d\u2019\u00e2ge\u00a0:\u00a0<\/strong>Ce que la musique nous enseigne avant tout, c\u2019est un autre rapport au temps, diff\u00e9rent de celui que nous connaissons dans la vie de tous les jours. Si elle est justement int\u00e9gr\u00e9e, cette exp\u00e9rience ne saurait se conjuguer avec des contraintes de temps quelles qu\u2019elles soient. Nos \u00e9coles permettent \u00e0 chacun de r\u00e9aliser son propre voyage int\u00e9rieur, en toute libert\u00e9. Respecter et prendre en compte cette r\u00e9alit\u00e9 intime \u00e0 chacun abolit de fait la notion de limite d\u2019\u00e2ge et repr\u00e9sente une des conditions premi\u00e8res d\u2019un enseignement musical authentique. Chacun apporte sa pierre au grand \u00e9difice de la musique, il ne saurait \u00eatre question de sup\u00e9riorit\u00e9 d\u2019une pierre sur l\u2019autre.<\/li>\n<li><strong>Le refus des examens\u00a0:\u00a0<\/strong>le pari de nos \u00e9coles n\u2019est pas de nier la discipline mais d\u2019affirmer que, sous sa forme authentique, elle s\u2019impose \u00e0 chacun comme une n\u00e9cessit\u00e9 int\u00e9rieure, et non comme une r\u00e8gle autoritaire impos\u00e9e de l\u2019ext\u00e9rieur. C\u2019est pourquoi la s\u00e9lection n\u2019a plus sa place, elle s\u2019op\u00e8re d\u2019elle-m\u00eame. En musique, il n\u2019est gu\u00e8re possible de tricher longtemps avec soi, ni avec les oeuvres. Discipline et s\u00e9lection d\u00e9coulent donc de la prise de conscience par chaque \u00e9l\u00e8ve de sa propre responsabilit\u00e9 face aux exigences inh\u00e9rentes \u00e0 la nature m\u00eame de la musique. Lib\u00e9r\u00e9 des pressions de la comp\u00e9tition, chacun pourra s\u2019ajuster au projet musical qu\u2019il fera sien, sans subir l\u2019\u00e9preuve d\u2019\u00eatre compar\u00e9.<\/li>\n<li><strong>La Ph\u00e9nom\u00e9nologie du son<\/strong> ouvre deux champs de recherche et d\u2019exp\u00e9rience. D&#8217;une part l\u2019ordre intrins\u00e8que des ph\u00e9nom\u00e8nes sonores et les lois physiques qui les r\u00e9gissent. D&#8217;autre part, le rapport entre ces relations sonores, la mani\u00e8re dont notre conscience les per\u00e7oit, et les effets qu&#8217;elles produisent dans notre monde affectif.<\/li>\n<li><strong>La Ph\u00e9nom\u00e9nologie du geste<\/strong> ouvre \u00e9galement deux champs de recherche et d\u2019exp\u00e9rience. Le premier est celui de l\u2019\u00e9tude du fonctionnement des muscles, de l\u2019utilisation du diaphragme et de la respiration dans le jeu ou la voix. Le second est l\u2019unification du phras\u00e9 musical par le geste et le souffle.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Un enseignement ouvert \u00e0 tous, sans examen, sans limite d&#8217;\u00e2ge et gratuit.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"aside","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6536","post","type-post","status-publish","format-aside","hentry","category-lacademie","post_format-post-format-aside"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9coles R\u00e9sonnance - Italie<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9coles R\u00e9sonnance - Italie\" \/>\n<meta property=\"og:description\" content=\"Un enseignement ouvert \u00e0 tous, sans examen, sans limite d&#039;\u00e2ge et gratuit.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/\" \/>\n<meta property=\"og:site_name\" content=\"Italie\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-23T10:37:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-13T16:19:48+00:00\" \/>\n<meta name=\"author\" content=\"jonas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"jonas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/\",\"url\":\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/\",\"name\":\"\u00c9coles R\u00e9sonnance - Italie\",\"isPartOf\":{\"@id\":\"https:\/\/www.resonnance.org\/it\/#website\"},\"datePublished\":\"2016-06-23T10:37:40+00:00\",\"dateModified\":\"2016-12-13T16:19:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.resonnance.org\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9coles R\u00e9sonnance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.resonnance.org\/it\/#website\",\"url\":\"https:\/\/www.resonnance.org\/it\/\",\"name\":\"Italie\",\"description\":\"Un monde en R\u00e9sonnance\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.resonnance.org\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb\",\"name\":\"jonas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g\",\"caption\":\"jonas\"},\"url\":\"http:\/\/www.resonnance.org\/it\/author\/jonas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9coles R\u00e9sonnance - Italie","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/","og_locale":"en_US","og_type":"article","og_title":"\u00c9coles R\u00e9sonnance - Italie","og_description":"Un enseignement ouvert \u00e0 tous, sans examen, sans limite d'\u00e2ge et gratuit.","og_url":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/","og_site_name":"Italie","article_published_time":"2016-06-23T10:37:40+00:00","article_modified_time":"2016-12-13T16:19:48+00:00","author":"jonas","twitter_card":"summary_large_image","twitter_misc":{"Written by":"jonas","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/","url":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/","name":"\u00c9coles R\u00e9sonnance - Italie","isPartOf":{"@id":"https:\/\/www.resonnance.org\/it\/#website"},"datePublished":"2016-06-23T10:37:40+00:00","dateModified":"2016-12-13T16:19:48+00:00","author":{"@id":"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb"},"breadcrumb":{"@id":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.resonnance.org\/it\/les-ecoles-resonnance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.resonnance.org\/it\/"},{"@type":"ListItem","position":2,"name":"\u00c9coles R\u00e9sonnance"}]},{"@type":"WebSite","@id":"https:\/\/www.resonnance.org\/it\/#website","url":"https:\/\/www.resonnance.org\/it\/","name":"Italie","description":"Un monde en R\u00e9sonnance","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.resonnance.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/40c99e385f4cf83a5a6dbc1d95a601bb","name":"jonas","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.resonnance.org\/it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d0970cc7fcad0b602d4a863ef0daade?s=96&d=mm&r=g","caption":"jonas"},"url":"http:\/\/www.resonnance.org\/it\/author\/jonas\/"}]}},"_links":{"self":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/posts\/6536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/comments?post=6536"}],"version-history":[{"count":0,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/posts\/6536\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/media?parent=6536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/categories?post=6536"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.resonnance.org\/it\/wp-json\/wp\/v2\/tags?post=6536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}